{"id":69,"count":10,"description":"","link":"https:\/\/divulgacion.ing.uc.cl\/en\/nivel_academico\/undergraduate-en\/","name":"Undergraduate Research","slug":"undergraduate-en","taxonomy":"nivel_academico","meta":[],"_links":{"self":[{"href":"https:\/\/divulgacion.ing.uc.cl\/en\/wp-json\/wp\/v2\/nivel_academico\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divulgacion.ing.uc.cl\/en\/wp-json\/wp\/v2\/nivel_academico"}],"about":[{"href":"https:\/\/divulgacion.ing.uc.cl\/en\/wp-json\/wp\/v2\/taxonomies\/nivel_academico"}],"wp:post_type":[{"href":"https:\/\/divulgacion.ing.uc.cl\/en\/wp-json\/wp\/v2\/posts?nivel_academico=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}